{"id":979,"date":"2020-12-28T17:15:38","date_gmt":"2020-12-28T17:15:38","guid":{"rendered":"http:\/\/actef.es\/?p=979"},"modified":"2021-04-20T15:25:57","modified_gmt":"2021-04-20T15:25:57","slug":"taller-de-escritura-creativa","status":"publish","type":"post","link":"https:\/\/actef.es\/web\/2020\/12\/28\/taller-de-escritura-creativa\/","title":{"rendered":"Taller de escritura creativa"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-753x1024.jpg\" alt=\"\" class=\"wp-image-1231\" width=\"277\" height=\"376\" srcset=\"https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-753x1024.jpg 753w, https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-221x300.jpg 221w, https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-768x1044.jpg 768w, https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-1130x1536.jpg 1130w, https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio-1506x2048.jpg 1506w, https:\/\/actef.es\/wp-content\/uploads\/2021\/04\/silencio.jpg 1624w\" sizes=\"auto, (max-width: 277px) 100vw, 277px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color: #9b51e0;\" class=\"ugb-highlight\">MU\u00d1ECO DIAB\u00d3LICO \u00a0 \u00a0 <\/span><\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <\/h2>\n\n\n\n<p>\u00a0 Nunca olvidar\u00e9 la tarde del 8 de noviembre, mis padres me llevaron al circo, de todos los n\u00fameros hubieron 2 que me llamaron la atenci\u00f3n, el domador de leones, que siempre me ha gustado y un payaso con un mu\u00f1eco un tanto siniestro, todos se fijaban en el mu\u00f1eco, yo me fij\u00e9 en el curioso tono rojizo de los ojos del payaso, le dije a mi madre:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Mam\u00e1, has visto el color\u2026<\/li><\/ul>\n\n\n\n<p>Pero no encontr\u00e9 a mi madre, sino al payaso y ahora era mi madre la que controla al mu\u00f1eco, justo antes de que comenzara a flotar en el aire y a hablar con voz siniestra , yo no ten\u00eda muy claro si hablaba el mu\u00f1eco o mi madre, yo apuesto por lo primero, dec\u00eda as\u00ed:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ma\u00f1ana deber\u00e9is traer algo grande y brillante.<\/li><\/ul>\n\n\n\n<p>Despu\u00e9s mi madre cay\u00f3 inconsciente, muerta, nadie lo sabe.<\/p>\n\n\n\n<p>Al d\u00eda siguiente le traje la medalla de atletismo del abuelo, que aunque no lo parezca, est\u00e1 muy en forma.<\/p>\n\n\n\n<p>Nadie sabe para qu\u00e9 quer\u00eda todos esos objetos, pero estoy seguro al 99,9% seguro de que cada d\u00eda faltan 3 hombres\/ni\u00f1os y 3 mujeres\/ni\u00f1as, y que cada d\u00eda el mu\u00f1eco parece m\u00e1s diab\u00f3lico y un poco m\u00e1s grande que el anterior.<\/p>\n\n\n\n<p>As\u00ed fueron pasando el tiempo hasta que solo quedamos yo, 2 ni\u00f1os mas y 3 ni\u00f1as mas, una vez le di mi copa favorita de nataci\u00f3n el mu\u00f1eco nos dijo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ten\u00e9is 10 minutos para huir.<\/li><\/ul>\n\n\n\n<p>Me fui corriendo tan r\u00e1pido como me permit\u00edan mis piernas, no sin antes echar una mirada a mi madre, que todav\u00eda estaba all\u00ed, en medio de la carpa, quieta.<\/p>\n\n\n\n<p>9 minutos, sal\u00ed del circo e intent\u00e9 escapar de la ciudad, pero ese maldito mu\u00f1eco hab\u00eda usado los objetos que le hab\u00edamos dado para hacer una muralla, los objetos se aguantan como por arte de magia o algo as\u00ed.<\/p>\n\n\n\n<p>7:30 minutos, voy al colegio, a esconderme en mi taquilla, cada 2 por 3 se oye un grito, supongo que el mu\u00f1eco sali\u00f3 de la carpa antes de tiempo, 5 minutos, se oye el \u00faltimo grito en la calle.<\/p>\n\n\n\n<p>4:30 minutos, la taquilla no es segura, me voy a mi clase y me asomo a la ventana y veo al mu\u00f1eco buscandome por la calle equivocada, 3 minutos, el mu\u00f1eco me busca corriendo, pero eso de ser mu\u00f1eco no tenia que ser f\u00e1cil, porque se paraba todo el rato, y, a cada paso, a cada suspiro, perd\u00eda fuerza.<\/p>\n\n\n\n<p>En ese momento pens\u00e9 2 cosas:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Que ese mu\u00f1eco tuvo que suspender educaci\u00f3n f\u00edsica, ya que no puede correr ni 5 minutos seguidos.<\/li><li>Que devoraba las almas de los que desaparecen, y que cuando perd\u00eda fuerzas, en verdad pierde almas, y un mu\u00f1eco diab\u00f3lico sin almas no es nada.<\/li><\/ol>\n\n\n\n<p>&nbsp;1 minuto, el mu\u00f1eco est\u00e1 buscando por la calle donde me encuentro. Y yo pienso en la gente a la que he perdido: mi madre, mi mejor amigo, mis dem\u00e1s amigos\u2026<\/p>\n\n\n\n<p>20 segundos, se acerca, lo noto, igual que el nota mi presencia, 10 segundos, entra en el colegio, 5 segundos, abre la puerta de mi clase, 2 segundos, me intenta tragar, 0 segundos. Finalmente,el mu\u00f1eco es como si se desactiva, como cuando apagas un electrodom\u00e9stico en mitad de su funcionamiento, cay\u00f3 al suelo justo antes de devorarme.<\/p>\n\n\n\n<p>Lo primero que hice fue asegurarme de que realmente estaba muerto, e ir al circo, sentarme al lado de mi madre y llorar, llorar por todo lo que me hab\u00eda pasado esta semana, desde la muerte de mi madre hasta que casi me come un mu\u00f1eco asesino. Escuch\u00e9 un gran estruendo fuera y fui a ver, el gran muro de oro se hab\u00eda derrumbado y fui a llamar a la polic\u00eda, que se asegur\u00f3 de quemar al mu\u00f1eco mientras yo, Francisco V\u00e1zquez, pensaba en mi madre, y, una vez m\u00e1s, llor\u00e9.<\/p>\n\n\n\n<p>Fin. \ud83d\ude42&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Blanca<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color: #9b51e0;\" class=\"ugb-highlight\">Suspiros del coraz\u00f3n<\/span><\/strong><\/h2>\n\n\n\n<p>Eres la nieve de mi vida,<br>el resplandor de mi coraz\u00f3n,<br>cuando te veo imagino,<br>que t\u00fa eres el sol,<br>eres el reflejo de la luna en mi ilusi\u00f3n.<\/p>\n\n\n\n<p>Cuando estoy contigo estamos en las estrellas<br>desde ellas vemos el amanecer<br>me recuerdas historias bonitas como los dos en la torre Eiffel,<br>a tu lado mi alma est\u00e1 en calma.<br>Y yo sigo siendo fiel.<\/p>\n\n\n\n<p>Eres el brillo de la luna<br>el silencio del desierto<br>la brisa de la colina<br>y el respiro que yo siento.<\/p>\n\n\n\n<p>Dar\u00edo Riera Martos (9 a\u00f1os)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong><span style=\"color: #9b51e0;\" class=\"ugb-highlight\">QUERIDO SANTA CLAUS, QUIERO UNA ESTRELLA:<\/span><\/strong><br>Ma\u00f1ana es Navidad, y como cada a\u00f1o voy a pedir una estrella, nunca me la traen, pero vale la pena intentarlo. Los dem\u00e1s ni\u00f1os de la clase me llaman \u00abRarito\u00bb, porque ellos siempre piden balones de f\u00fatbol o videojuegos, y yo pido una estrella, pero nunca me la traen, siempre me traen o un peluche de estrella o una manta de estrella, por eso este a\u00f1o he especificado m\u00e1s y antes de enviarla al Polo Norte he a\u00f1adido:<br>\u00abQuiero una estrella de verdad\u00bb.<br>A la ma\u00f1ana siguiente me sorprend\u00ed mucho al no encontrar ning\u00fan paquete, solamente a un ni\u00f1o que brillaba mucho.<br>-Hola -me dijo- \u00bfC\u00f3mo te llamas?-Manolo, y t\u00fa? -le dije yo-Lani, Lani la Estrella.<br>Estaba tan embobado contempl\u00e1ndole que no pens\u00e9 c\u00f3mo es que hablaba el mismo idioma que yo.<br>Cuando le pregunt\u00e9 de d\u00f3nde ven\u00eda me dijo:<br>-Del espacio, pero hace poco vino un se\u00f1or gordo con barba blanca y un carro tirado por renos y me trajo aqu\u00ed.-Bobo,-le dije yo- ese \u00abse\u00f1or gordo\u00bb es Santa Claus.-\u00bfSanta Claus?-me dijo.-Si Santa Claus, es como un duende que una vez al a\u00f1o nos trae regalos a los ni\u00f1os.<br>Despu\u00e9s de pasar un rato con Lani tuve una idea genial:<br>-\u00a1Lani ven!, Vamos a hacer galletas.<br>Despu\u00e9s de explicarle lo que son las galletas y asegurarle que no eran venenosas las hicimos y quedaron buen\u00edsimas.<br>En cuanto se hizo de noche Lani desapareci\u00f3 y una estrella volvi\u00f3 a brillar en el cielo.<br>Desde ese d\u00eda y a\u00fan lo hago (28 a\u00f1os m\u00e1s tarde) siempre pido para navidad:<br>\u00abQuerido Santa Claus, este a\u00f1o quiero a Lani\u00bb.<br>Y cuando lo veo charlamos, hacemos galletas y yo ya me he acostumbrado a ver desaparecer una estrella una noche al a\u00f1o, para volver a aparecer a la noche siguiente.<br>Y no me preocupo, porque \u00e9l crece conmigo y lo puedo ver una vez al a\u00f1o.<\/p>\n\n\n\n<p><strong>Blanca, 10 a\u00f1os<\/strong><\/p>\n\n\n\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-_0bd8a9-1e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\" style=\"height:60px\"><hr class=\"kt-divider\" style=\"border-top-color:rgba(238, 238, 238, 1);border-top-width:1px;width:80%;border-top-style:solid\"\/><\/div><\/div>\n\n\n\n<h1 class=\"has-medium-font-size wp-block-heading\"><span style=\"color: #9b51e0;\" class=\"ugb-highlight\">EL CONEJO BERNARDO<\/span><\/h1>\n\n\n\n<p>Hace mucho tiempo&nbsp; naci\u00f3 en un gran valle, dentro de una c\u00e1lida madriguera, un peque\u00f1o belier, que es un conejo con orejas ca\u00eddas.<\/p>\n\n\n\n<p>Ten\u00eda dos hermanos blancos como \u00e9l y sus padres eran de color marr\u00f3n.<\/p>\n\n\n\n<p>Era su primera navidad y Bernardo estaba aburrido porque sus padres estaban s\u00faper ocupados con los adornos navide\u00f1os y preparando la comida para hibernar.<\/p>\n\n\n\n<p>Entonces decidi\u00f3 escaparse para hacer nuevos amigos. Se encontr\u00f3 en medio del valle un conejo joven como \u00e9l, que se llamaba Eloy, color canela con las orejas para arriba.<\/p>\n\n\n\n<p>Eloy quiso ense\u00f1arle el valle cuando de repente aparecieron dos cazadores, los cogieron y se los llevaron a su casa para com\u00e9rselos.<\/p>\n\n\n\n<p>Cuando llegaron a su casa, los metieron en una jaula, el hijo de un cazador que le encantaban los animales y no le gustaba que los mataran, vio a los peque\u00f1os conejos y le dio mucha pena, as\u00ed que se los llevo a su habitaci\u00f3n a escondidas, aprovech\u00f3 un descuido de su padre para liberar a los conejos en el Valle.<\/p>\n\n\n\n<p>Los dos conejos corrieron a la madriguera de Bernardo y como Eloy no ten\u00eda padres se convirti\u00f3&nbsp; en uno m\u00e1s de la familia.<\/p>\n\n\n\n<p>Los dos conejos aprendieron a no meterse en l\u00edos y pasaron una muy feliz navidad.<\/p>\n\n\n\n<p>Autora:<\/p>\n\n\n\n<p><strong>Martina Jim\u00e9nez\u00a0, 7 a\u00f1os<\/strong><\/p>\n\n\n\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-_d86574-0c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\" style=\"height:60px\"><hr class=\"kt-divider\" style=\"border-top-color:rgba(238, 238, 238, 1);border-top-width:1px;width:80%;border-top-style:solid\"\/><\/div><\/div>\n\n\n\n<p><\/p>\n<style class=\"advgb-styles-renderer\">.wp-block-kadence-spacer.kt-block-spacer-_0bd8a9-1e .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-_0bd8a9-1e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}.wp-block-kadence-spacer.kt-block-spacer-_d86574-0c .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-_d86574-0c .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>","protected":false},"excerpt":{"rendered":"<p>MU\u00d1ECO DIAB\u00d3LICO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Nunca olvidar\u00e9 la tarde del &#8230; <a title=\"Taller de escritura creativa\" class=\"read-more\" href=\"https:\/\/actef.es\/web\/2020\/12\/28\/taller-de-escritura-creativa\/\" aria-label=\"Leer m\u00e1s sobre Taller de escritura creativa\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"featured_image_urls_v2":{"full":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1.jpg",960,720,false],"thumbnail":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1-150x150.jpg",150,150,true],"medium":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1-300x225.jpg",300,225,true],"medium_large":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1-768x576.jpg",768,576,true],"large":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1.jpg",960,720,false],"1536x1536":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1.jpg",960,720,false],"2048x2048":["https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1.jpg",960,720,false]},"post_excerpt_stackable_v2":"<p>MU\u00d1ECO DIAB\u00d3LICO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Nunca olvidar\u00e9 la tarde del 8 de noviembre, mis padres me llevaron al circo, de todos los n\u00fameros hubieron 2 que me llamaron la atenci\u00f3n, el domador de leones, que siempre me ha gustado y un payaso con un mu\u00f1eco un tanto siniestro, todos se fijaban en el mu\u00f1eco, yo&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/actef.es\/web\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","author_info_v2":{"name":"Esperanza Marqu\u00e8s","url":"https:\/\/actef.es\/web\/author\/esperanza\/"},"comments_num_v2":"0 comentarios","author_meta":{"display_name":"Esperanza Marqu\u00e8s","author_link":"https:\/\/actef.es\/web\/author\/esperanza\/"},"featured_img":"https:\/\/actef.es\/wp-content\/uploads\/2020\/12\/Presentacion1-1-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/actef.es\/web\/category\/noticias\/\" class=\"advgb-post-tax-term\">Noticias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Noticias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 5 a\u00f1os hace","modified":"Actualizado 5 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 28 diciembre 2020","modified":"Actualizado el 20 abril 2021"},"absolute_dates_time":{"created":"Publicado el 28 diciembre 2020 17:15","modified":"Actualizado el 20 abril 2021 15:25"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/posts\/979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/comments?post=979"}],"version-history":[{"count":7,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/posts\/979\/revisions"}],"predecessor-version":[{"id":1235,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/posts\/979\/revisions\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/media\/985"}],"wp:attachment":[{"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/media?parent=979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/categories?post=979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actef.es\/web\/wp-json\/wp\/v2\/tags?post=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}